{"id":1465,"date":"2019-07-01T09:17:21","date_gmt":"2019-07-01T08:17:21","guid":{"rendered":"https:\/\/www.canlluc.com\/blog\/?p=1465"},"modified":"2019-07-22T11:36:23","modified_gmt":"2019-07-22T10:36:23","slug":"hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores","status":"publish","type":"post","link":"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/","title":{"rendered":"Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores"},"content":{"rendered":"<p><strong>\u00a0La saxofonista Anastasia McQueen, el guionista Davis Marqu\u00e9s, la soprano Irantxu Bartolom\u00e9 y el violinista Linus Roth, nuevos embajadores de Ibiza Luxury Destination.<\/strong><\/p>\n<p><strong>\u2022 El sello Ibiza Luxury Destination est\u00e1 integrado por 48 establecimientos que ofrecen al turista la posibilidad de vivir el lujo de la isla.<\/strong><\/p>\n<div class=\"wysiwyg-photo\"><img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/static.hosteltur.com\/app\/public\/uploads\/img\/releases\/2019\/07\/11\/L_130426_fiesta-ild.jpg\" alt=\"Imagen nota de prensa Hosteltur\" width=\"3264\" height=\"1813\" \/><\/div>\n<p>Existen tantas Ibizas como personas que la visitan. Cada una de ellas interpreta la isla de una forma distinta y el simple hecho de estar en la Isla Blanca es ya todo un lujo. Con esta premisa, la sociedad ibicenca se ha dado cita esta noche en el hotel 7 Pines Resort Ibiza para acudir a la presentaci\u00f3n del cat\u00e1logo de esta edici\u00f3n y conocer a los nuevos embajadores del sello de calidad Ibiza Luxury Destination. Ha abierto la noche la maestra de ceremonias y actriz B\u00e1rbara Hermosilla, dando paso a Carlos Fritz, director del hotel 7 Pines, anfitriones del evento, que agradeci\u00f3 la asistencia a todos los invitados al evento, entre ellos, Carlos Martorell, pionero y fundador de la famosa discoteca Pacha de Ibiza.<\/p>\n<p>La Presidenta de Ibiza Luxury Destination, Marina Amor\u00f3s, ha presentado la novena edici\u00f3n del cat\u00e1logo Ibiza Luxury Destination, cuya primera edici\u00f3n se lanz\u00f3 en diciembre de 2010 con 34 empresas, y que ha ido creciendo a\u00f1o tras a\u00f1o hasta llegar a las 48 de hoy en d\u00eda. Todas ellas pasan un filtro para incorporarse al club y tienen sobradamente demostrado que cumplen con los criterios de calidad que exigen, tanto los clientes como la normativa.<\/p>\n<p>Marina Amor\u00f3s ha asegurado que \u201cen este grupo defendemos que el turismo de lujo es tan v\u00e1lido, o m\u00e1s, como cualquier otro. Ibiza recibe a todos y todos encuentran su espacio, pero, adem\u00e1s, los miembros del club Ibiza Luxury Destination nos esforzamos por poner en valor y dar a conocer los recursos de los que dispone la isla para que nuestros visitantes se lleven la mejor de las im\u00e1genes\u201d. Y subray\u00f3 que \u201crespaldamos todas las iniciativas en favor de la sostenibilidad y mejora del medioambiente. En nuestras empresas han empezado a eliminarse pl\u00e1sticos de un solo uso, se realizan campa\u00f1as de limpieza de playas, se informa sobre los fondeos evitando las praderas de posidonia o se usan productos km0 y plantas de nuestros campos, entre otras muchas actuaciones. Con todo eso, nuestro slogan de que El lujo es estar en Ibiza se hace realidad, no solo para nuestros visitantes, sino tambi\u00e9n para nosotros los residentes\u201d.<\/p>\n<p>Entre las 48 empresas que forman Ibiza Luxury Destination, se encuentran compa\u00f1\u00edas del sector hotelero, de la restauraci\u00f3n o del sector servicios. Agroturismos como Can Lluc o Can Curreu; hoteles como Hacienda Na Xamena, Hard Rock Hotel, Ush\u00fcaia Ibiza Beach Hotel o Sir Joan Hotel; empresas de transporte, como Ibiza Gran Turismo o Luxive Dipesa; alquiler y venta de villas, como Ibiza Country Villas o Ecoibiza; de servicios, como The Chef Ibiza o The Ibiza Wedding Planner; y restaurantes, como Nassau Beach Club, Tatel Ibiza, Zela o H\u00ef Ibiza buscan ofrecer los mejores servicios en la isla.<\/p>\n<p>Algo que conocen de primera mano los embajadores del sello, que ya suman 36. Personas conocidas por su trayectoria profesional, para los que Ibiza es un lugar especial y les apasiona la isla. Algunos de los anteriores embajadores estuvieron presentes, como el dj Sebasti\u00e1n Gamboa. En la fiesta, se dieron a conocer los nuevos nombres: la saxofonista Anastasia McQueen, el guionista Davis Marqu\u00e9s, la soprano Irantzu Bartolom\u00e9 y el violinista Linus Roth.<\/p>\n<p>As\u00ed, Anastasia McQueen que, adem\u00e1s puso la nota musical de la noche, es muy conocida en el Ibiza y en todo el mundo, por sus actuaciones en directo. Actualmente, es residente de la fiesta Vintage by Sebastian Gamboa. Anastasia compagina su carrera musical con su empresa Q Ibiza especializada en deportes acu\u00e1ticos y eventos.<\/p>\n<p>El ibicenco David Marqu\u00e9s es guionista, director, autor teatral&#8230; Este a\u00f1o ha sido el autor del guion de Campeones, dirigida por Javier Fesser, el mayor \u00e9xito comercial y cr\u00edtico del cine espa\u00f1ol de 2018. Por este trabajo ha sido nominado al Goya al Mejor Guion Original, y se le ha concedido el Premio Nacional del Deporte aplicado a la Artes y las Ciencias. La soprano Irantzu Bartolom\u00e9 reside en Ibiza compaginando su trabajo de solista con el de profesora de canto en el coro Ciudad de Ibiza y en las escuelas municipales del Patronato Municipal de M\u00fasica de Ibiza y de Can Blau en San Agust\u00ed.<\/p>\n<p>En septiembre, debutar\u00e1 con el papel de Nedda de la \u00f3pera Pagliacci de R. Leoncavallo en la \u00f3pera de Fuerteventura. Cerrar\u00e1 este a\u00f1o el ciclo de las Nits del Museo de Etnograf\u00eda 2019 de Santa Eul\u00e0ria des Riu. Linus Roth es uno de los violinistas cl\u00e1sicos m\u00e1s fascinantes de su generaci\u00f3n. Es el fundador y director art\u00edstico de Festival Ibiza Concerts, una serie anual de conciertos que tienen lugar en el Claustro de Eivissa en Dalt Vila. Es profesor de viol\u00edn en la Universidad de Augsburg, fundador de la International Weinberg Society y del Festival Schw\u00e4bischer Fr\u00fchling en Alemania.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0La saxofonista Anastasia McQueen, el guionista Davis Marqu\u00e9s, la soprano Irantxu Bartolom\u00e9 y el violinista Linus Roth, nuevos embajadores de Ibiza Luxury Destination. \u2022 El sello Ibiza Luxury Destination est\u00e1 integrado por 48 establecimientos que ofrecen al turista la posibilidad de vivir el lujo de la isla. Existen tantas Ibizas como personas que la visitan. &#8230; <a title=\"Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores\" class=\"read-more\" href=\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\" aria-label=\"M\u00e1s en Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":1474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[143],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores - Can Lluc | Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores - Can Lluc | Blog\" \/>\n<meta property=\"og:description\" content=\"\u00a0La saxofonista Anastasia McQueen, el guionista Davis Marqu\u00e9s, la soprano Irantxu Bartolom\u00e9 y el violinista Linus Roth, nuevos embajadores de Ibiza Luxury Destination. \u2022 El sello Ibiza Luxury Destination est\u00e1 integrado por 48 establecimientos que ofrecen al turista la posibilidad de vivir el lujo de la isla. Existen tantas Ibizas como personas que la visitan. ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\" \/>\n<meta property=\"og:site_name\" content=\"Can Lluc | Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-01T08:17:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-07-22T10:36:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/07\/Captura.png\" \/>\n\t<meta property=\"og:image:width\" content=\"755\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\">\n\t<meta name=\"twitter:data1\" content=\"Can Lluc\">\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" content=\"3 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#website\",\"url\":\"https:\/\/www.canlluc.com\/blog\/\",\"name\":\"Can Lluc | Blog\",\"description\":\"Historias mediterr\\u00e1neas, calma junto al mar y experiencias en Ibiza\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.canlluc.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/07\/Captura.png\",\"width\":755,\"height\":428},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/#webpage\",\"url\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\",\"name\":\"Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores - Can Lluc | Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/#primaryimage\"},\"datePublished\":\"2019-07-01T08:17:21+00:00\",\"dateModified\":\"2019-07-22T10:36:23+00:00\",\"author\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/#\/schema\/person\/d1f0ed1fabfe2418dbb130903246f8f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/\",\"url\":\"https:\/\/www.canlluc.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\",\"url\":\"https:\/\/www.canlluc.com\/blog\/hosteltur-ibiza-luxury-destination-presenta-sus-nuevos-embajadores\/\",\"name\":\"Hosteltur: Ibiza Luxury Destination presenta a sus nuevos embajadores\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#\/schema\/person\/d1f0ed1fabfe2418dbb130903246f8f4\",\"name\":\"Can Lluc\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6d6f4ca47e6f2202cafd25ec9fb69261?s=96&d=mm&r=g\",\"caption\":\"Can Lluc\"},\"sameAs\":[\"https:\/\/www.canlluc.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1465"}],"collection":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/comments?post=1465"}],"version-history":[{"count":4,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1465\/revisions"}],"predecessor-version":[{"id":1473,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1465\/revisions\/1473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/media\/1474"}],"wp:attachment":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/media?parent=1465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/categories?post=1465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/tags?post=1465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}