{"id":1178,"date":"2019-02-22T11:11:38","date_gmt":"2019-02-22T10:11:38","guid":{"rendered":"http:\/\/www.canlluc.com\/blog\/?p=1178"},"modified":"2019-04-16T08:49:47","modified_gmt":"2019-04-16T07:49:47","slug":"el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda","status":"publish","type":"post","link":"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/","title":{"rendered":"El escenario m\u00e1s id\u00edlico de Ibiza para celebrar una boda"},"content":{"rendered":"<p>Inout viajes nos ha dedicado un reportaje maravilloso hablando sobre lo que Can Lluc quiere transmitir en cada boda: Tranquilidad, romanticismo y delicadeza: \u00abEl valle de\u00a0<a href=\"https:\/\/www.ibiza5sentidos.es\/visita-ibiza\/sant-rafel-de-sa-creu\/\" target=\"_blank\" rel=\"noopener noreferrer\">San Rafael<\/a>\u00a0se convierte en el contexto de fondo, donde los pinos y algarrobos envuelven el ambiente. Un ambiente perfecto para celebrar tu boda en esta casa payesa, donde poder elegir entre una gama de variadas habitaciones llenas de encanto para alojar a tus invitados\u00bb<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1179\" src=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/Can-lluc-1-209x300.png\" alt=\"\" width=\"209\" height=\"300\" srcset=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/Can-lluc-1-209x300.png 209w, https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/Can-lluc-1.png 539w\" sizes=\"(max-width: 209px) 100vw, 209px\" \/><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1181\" src=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/can-lluc-2-300x132.png\" alt=\"\" width=\"300\" height=\"132\" srcset=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/can-lluc-2-300x132.png 300w, https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/can-lluc-2.png 549w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inout viajes nos ha dedicado un reportaje maravilloso hablando sobre lo que Can Lluc quiere transmitir en cada boda: Tranquilidad, romanticismo y delicadeza: \u00abEl valle de\u00a0San Rafael\u00a0se convierte en el contexto de fondo, donde los pinos y algarrobos envuelven el ambiente. Un ambiente perfecto para celebrar tu boda en esta casa payesa, donde poder elegir &#8230; <a title=\"El escenario m\u00e1s id\u00edlico de Ibiza para celebrar una boda\" class=\"read-more\" href=\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\" aria-label=\"M\u00e1s en El escenario m\u00e1s id\u00edlico de Ibiza para celebrar una boda\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":2,"featured_media":1183,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[143],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El escenario m\u00e1s id\u00edlico de Ibiza para celebrar una boda - Can Lluc | Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El escenario m\u00e1s id\u00edlico de Ibiza para celebrar una boda - Can Lluc | Blog\" \/>\n<meta property=\"og:description\" content=\"Inout viajes nos ha dedicado un reportaje maravilloso hablando sobre lo que Can Lluc quiere transmitir en cada boda: Tranquilidad, romanticismo y delicadeza: \u00abEl valle de\u00a0San Rafael\u00a0se convierte en el contexto de fondo, donde los pinos y algarrobos envuelven el ambiente. Un ambiente perfecto para celebrar tu boda en esta casa payesa, donde poder elegir ... Leer m\u00e1s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\" \/>\n<meta property=\"og:site_name\" content=\"Can Lluc | Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-22T10:11:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-16T07:49:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/27018015948_1d4a54ab81_o-1024x683.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\">\n\t<meta name=\"twitter:data1\" content=\"Can Lluc\">\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\">\n\t<meta name=\"twitter:data2\" content=\"0 minutos\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#website\",\"url\":\"https:\/\/www.canlluc.com\/blog\/\",\"name\":\"Can Lluc | Blog\",\"description\":\"Historias mediterr\\u00e1neas, calma junto al mar y experiencias en Ibiza\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.canlluc.com\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.canlluc.com\/blog\/wp-content\/uploads\/2019\/02\/27018015948_1d4a54ab81_o.jpg\",\"width\":1920,\"height\":1281},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/#webpage\",\"url\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\",\"name\":\"El escenario m\\u00e1s id\\u00edlico de Ibiza para celebrar una boda - Can Lluc | Blog\",\"isPartOf\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/#primaryimage\"},\"datePublished\":\"2019-02-22T10:11:38+00:00\",\"dateModified\":\"2019-04-16T07:49:47+00:00\",\"author\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/#\/schema\/person\/d1f0ed1fabfe2418dbb130903246f8f4\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/\",\"url\":\"https:\/\/www.canlluc.com\/blog\/\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\",\"url\":\"https:\/\/www.canlluc.com\/blog\/el-escenario-mas-idilico-de-ibiza-para-celebrar-una-boda\/\",\"name\":\"El escenario m\\u00e1s id\\u00edlico de Ibiza para celebrar una boda\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#\/schema\/person\/d1f0ed1fabfe2418dbb130903246f8f4\",\"name\":\"Can Lluc\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.canlluc.com\/blog\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/6d6f4ca47e6f2202cafd25ec9fb69261?s=96&d=mm&r=g\",\"caption\":\"Can Lluc\"},\"sameAs\":[\"https:\/\/www.canlluc.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1178"}],"collection":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/comments?post=1178"}],"version-history":[{"count":2,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions"}],"predecessor-version":[{"id":1187,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/posts\/1178\/revisions\/1187"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/media\/1183"}],"wp:attachment":[{"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/media?parent=1178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/categories?post=1178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.canlluc.com\/blog\/wp-json\/wp\/v2\/tags?post=1178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}